{"id":353,"date":"2010-08-10T12:23:00","date_gmt":"2010-08-10T12:23:00","guid":{"rendered":"http:\/\/talasoatlantico.com\/blog\/?p=353"},"modified":"2013-11-23T16:05:36","modified_gmt":"2013-11-23T16:05:36","slug":"as-bagoas-de-san-lourenzo-traen-ate-100-meteoros-a-hora","status":"publish","type":"post","link":"https:\/\/www.talasoatlantico.com\/blog\/as-bagoas-de-san-lourenzo-traen-ate-100-meteoros-a-hora\/","title":{"rendered":"As \u2018B\u00e1goas de San Lourenzo\u2019 traen at\u00e9 100 meteoros \u00e1 hora"},"content":{"rendered":"<p><a href=\"http:\/\/3.bp.blogspot.com\/_u_dwr43mzZg\/TGFFayt4oQI\/AAAAAAAAAMs\/uue706Ph64s\/s1600\/b%C3%83%C2%A1goa.jpg\"><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_u_dwr43mzZg\/TGFFayt4oQI\/AAAAAAAAAMs\/uue706Ph64s\/s320\/b%C3%83%C2%A1goa.jpg\" border=\"0\" alt=\"\"><\/a><\/p>\n<div><span><span>OS D\u00cdAS 12 E 13 DE AGOSTO<\/span><\/span><\/div>\n<div><span><span><b>As \u2018B\u00e1goas de San Lourenzo\u2019 traen at\u00e9 100 meteoros \u00e1 hora<\/b><\/span><\/span><\/div>\n<p><span><span><span>Redacci\u00f3n .  <\/span><\/span><\/span><span><span>O fen\u00f3meno astron\u00f3mico anual co\u00f1ecido popularmente como \u2018B\u00e1goas de San Lourenzo\u2019 permiri\u00e1 observar este xoves e venres, 12 e 13 de agosto, a\u00b4te 100 meteoros \u00e1 hora, momento no que se producir\u00e1 o momento \u00e1lxido desta chuvia de estrelas.<\/span><\/span><\/p>\n<\/p>\n<div><span>Cient\u00edficamente denominadas como Perseidas, este fen\u00f3meno est\u00e1 en activo dende o pasado 16 de xullo, pero non ser\u00e1 at\u00e9 este xoves e venres cando se produza con maior intensidade at\u00e9 a s\u00faa desaparici\u00f3n o 24 de agosto, cando a Terra deixe de estar dentro da nube de part\u00edculas de influenza.<\/span><\/div>\n<p><span><\/p>\n<div><span><br \/><\/span><\/div>\n<p><span><\/p>\n<div><span><span><span>As B\u00e1goas de San Lourenzo \u00e9 un fen\u00f3meno que ten lugar cando a Terra, na s\u00faa \u00f3rbita arredor do Sol, pasa por unha nube de part\u00edculas que foi xerada polo cometa <\/span><\/span><em><span><span>Swift Tutlle<\/span><\/span><\/em><span><span> e que est\u00e1 estacionaria no mesmo lugar, por iso a visi\u00f3n da chuvia de meteroros se produce cada ver\u00e1n m\u00e1is ou menos nas mesmas datas.<\/span><\/span><\/span><\/div>\n<p><\/span><\/span><span><\/p>\n<div><span><br \/><\/span><\/div>\n<p><span><\/p>\n<div><\/div>\n<div><span><span><span>A \u00faltima vez que o<\/span><\/span><em><span><span> Swift Tuttle<\/span><\/span><\/em><span><span> pasou cerca do Sol foi no ano 1992, polo que o pico m\u00e1is alto de chuvia de meteoros produciuse no ano 1993, ano no que se contabilizaron 400 meteroros \u00e1 hora.<\/span><\/span><\/span><\/div>\n<p><\/span><\/span><span><\/p>\n<div><span><br \/><\/span><\/div>\n<p><span><\/p>\n<div><\/div>\n<p><\/span><\/span><strong><\/p>\n<div><span><strong><span><span>Recomendaci\u00f3ns<\/span><\/span><\/strong><\/span><\/div>\n<p><\/strong><span><\/p>\n<div><span><br \/><\/span><\/div>\n<p><span><\/p>\n<div>Para poder visionar a chuvia de estrelas de San Lourenzo os expertos recomendan \u201ca simple vista\u201d, sen axuda de prism\u00e1ticos nin telescopios. Iso si, o espectador deber\u00e1 dirixir a vista en direcci\u00f3n noroeste, cara a Constelaci\u00f3n de Perseo pasadas as 23h00 e durante a madrugada.<\/div>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OS D\u00cdAS 12 E 13 DE AGOSTO As \u2018B\u00e1goas de San Lourenzo\u2019 traen at\u00e9 100 meteoros \u00e1 hora Redacci\u00f3n . O fen\u00f3meno astron\u00f3mico anual co\u00f1ecido popularmente como \u2018B\u00e1goas de San Lourenzo\u2019 permiri\u00e1 observar este xoves e venres, 12 e 13 de agosto, a\u00b4te 100 meteoros \u00e1 hora, momento no que se producir\u00e1 o momento \u00e1lxido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[49,9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/353"}],"collection":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/comments?post=353"}],"version-history":[{"count":1,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/353\/revisions"}],"predecessor-version":[{"id":1120,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/353\/revisions\/1120"}],"wp:attachment":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/media?parent=353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/categories?post=353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/tags?post=353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}