{"id":380,"date":"2010-05-18T07:02:00","date_gmt":"2010-05-18T07:02:00","guid":{"rendered":"http:\/\/talasoatlantico.com\/blog\/?p=380"},"modified":"2013-11-23T16:09:08","modified_gmt":"2013-11-23T16:09:08","slug":"estoy-escondido-shsss","status":"publish","type":"post","link":"https:\/\/www.talasoatlantico.com\/blog\/estoy-escondido-shsss\/","title":{"rendered":"Estoy escondido, shsss&#8230;"},"content":{"rendered":"<div><a href=\"http:\/\/2.bp.blogspot.com\/_u_dwr43mzZg\/S_I7f7JuuiI\/AAAAAAAAAJs\/_XDpi98SqY0\/s1600\/FxCam_1274113507361.jpg\"><img decoding=\"async\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_u_dwr43mzZg\/S_I7f7JuuiI\/AAAAAAAAAJs\/_XDpi98SqY0\/s400\/FxCam_1274113507361.jpg\" border=\"0\"><\/a> <\/div>\n<p><span>Situaciones de parque Infantil I<\/span><\/p>\n<div><span><br \/><\/span><\/div>\n<div><span>\u00abEstoy escondido\u00bb. Este misterioso mensaje en clave se lo dej\u00f3 un ni\u00f1o que estaba jugando en la Guarder\u00eda a nuestra compa\u00f1era Paula. Era un recado para el hemano peque\u00f1o de \u00e9ste. La conversaci\u00f3n tuvo que transcurrir, m\u00e1s o menos, de la manera que sigue:<\/p>\n<p>Ni\u00f1o1.- Dale esto a mi hermano.<br \/>Paula.- A ver&#8230;- coge el papel, lo lee y levanta una ceja mientras va cambiando su cara-, \u00bfy esto?<br \/>Ni\u00f1o1.- D\u00e1selo a mi hermano peque\u00f1o. Y l\u00e9eselo&#8230;\u00e9l no sabe leer&#8230;<\/span><\/div>\n<div><span><br \/><\/span><\/div>\n<div><span>\u00bfEs o no es buen\u00edsimo?<\/span><\/div>\n<div><span><br \/><\/span><\/div>\n<div><span>&#8230;el mundo de esos locos bajitos&#8230;<br \/><\/span><\/p>\n<div><a href=\"http:\/\/picasa.google.com\/blogger\/\" target=\"ext\"><img decoding=\"async\" src=\"http:\/\/photos1.blogger.com\/pbp.gif\" alt=\"Posted by Picasa\" align=\"middle\" border=\"0\"><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Situaciones de parque Infantil I \u00abEstoy escondido\u00bb. Este misterioso mensaje en clave se lo dej\u00f3 un ni\u00f1o que estaba jugando en la Guarder\u00eda a nuestra compa\u00f1era Paula. Era un recado para el hemano peque\u00f1o de \u00e9ste. La conversaci\u00f3n tuvo que transcurrir, m\u00e1s o menos, de la manera que sigue: Ni\u00f1o1.- Dale esto a mi hermano.Paula.- [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[48],"tags":[],"_links":{"self":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/380"}],"collection":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/comments?post=380"}],"version-history":[{"count":1,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/380\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/380\/revisions\/1137"}],"wp:attachment":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/media?parent=380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/categories?post=380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/tags?post=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}