{"id":387,"date":"2010-05-13T15:31:00","date_gmt":"2010-05-13T15:31:00","guid":{"rendered":"http:\/\/talasoatlantico.com\/blog\/?p=387"},"modified":"2013-11-23T16:09:51","modified_gmt":"2013-11-23T16:09:51","slug":"factores-que-utiliza-la-talasoterapia-v-peloideterapia","status":"publish","type":"post","link":"https:\/\/www.talasoatlantico.com\/blog\/factores-que-utiliza-la-talasoterapia-v-peloideterapia\/","title":{"rendered":"Factores que utiliza la talasoterapia &#8211; V Peloideterapia"},"content":{"rendered":"<p><a href=\"http:\/\/3.bp.blogspot.com\/_u_dwr43mzZg\/S-wdkoh6grI\/AAAAAAAAAJM\/So4E2Rt1Bhc\/s1600\/El+mar+todo+lo+cura.jpg\"><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_u_dwr43mzZg\/S-wdkoh6grI\/AAAAAAAAAJM\/So4E2Rt1Bhc\/s320\/El+mar+todo+lo+cura.jpg\" border=\"0\" alt=\"\"><\/a><br \/><b><span lang=\"ES-TRAD\">PELOIDETERAPIA<\/span><\/b><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Entendemos por Peloideterapia la utilizaci\u00f3n de los peloides con fines terap\u00e9uticos. En Talasoterapia se utilizan los llamados lomos marinos, barros o limos.<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Composici\u00f3n.- Son sustancias de consistencia pastosa que se extraen del fondo del mar, compuestas por una mezcla de agua de mar, sedimentos org\u00e1nicos procedentes de la descomposici\u00f3n de algas, peces, moluscos y sedimentos inorg\u00e1nicos arcillosos mezclados con arenas.<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Entre sus propiedades es rese\u00f1able resaltar su gran plasticidad, el poder de retenci\u00f3n de calor y de agua y el hecho de que enfr\u00eden muy lentamente.<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Los efectos se diferencian entre:<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><span>1.<span>    <\/span><\/span><\/span><span lang=\"ES-TRAD\">Locales.-<\/p>\n<p><\/span><\/p>\n<ul type=\"disc\">\n<li><span lang=\"ES-TRAD\">Aumento de la temperatura en el punto de aplicaci\u00f3n.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Vasodilatador e hiperemia local.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Decontracturante muscular.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Analg\u00e9sico.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Facilitan la reabsorci\u00f3n de edemas.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Fortalecen la piel: remineralizan los tejidos.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Da elasticidad a los tejidos.\n<\/p>\n<p><\/span><\/li>\n<\/ul>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><span>2.<span>    <\/span><\/span><\/span><span lang=\"ES-TRAD\">Generales:<\/p>\n<p><\/span><\/p>\n<ul type=\"disc\">\n<li><span lang=\"ES-TRAD\">Elevaci\u00f3n de la temperatura corporal, facilitan la sudoraci\u00f3n y la eliminaci\u00f3n de toxinas.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Aumento de la frecuencia respiratoria y del ritmo cardiaco.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Hipotensi\u00f3n arterial\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Incremento de las respuestas inmunol\u00f3gicas.\n<\/p>\n<p><\/span><\/li>\n<li><span lang=\"ES-TRAD\">Determina reacciones de precipitaci\u00f3n, oxidaci\u00f3n y reducci\u00f3n.\n<\/p>\n<p><\/span><\/li>\n<\/ul>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Las t\u00e9cnicas m\u00e1s habituales con las envolturas parciales, locales o generales. As\u00ed mismo, tambi\u00e9n son habituales los ba\u00f1os.<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\">Indicaciones: Artrosis \u2013 artritis, problemas musculares, de tendones, problemas dermatol\u00f3gicos (psoriaris)\u2026<\/p>\n<p><\/span><\/p>\n<p><span lang=\"ES-TRAD\"><\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PELOIDETERAPIA Entendemos por Peloideterapia la utilizaci\u00f3n de los peloides con fines terap\u00e9uticos. En Talasoterapia se utilizan los llamados lomos marinos, barros o limos. Composici\u00f3n.- Son sustancias de consistencia pastosa que se extraen del fondo del mar, compuestas por una mezcla de agua de mar, sedimentos org\u00e1nicos procedentes de la descomposici\u00f3n de algas, peces, moluscos y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/387"}],"collection":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":1,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/387\/revisions"}],"predecessor-version":[{"id":1141,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/387\/revisions\/1141"}],"wp:attachment":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/media?parent=387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/categories?post=387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/tags?post=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}