{"id":414,"date":"2010-03-23T00:55:00","date_gmt":"2010-03-23T00:55:00","guid":{"rendered":"http:\/\/talasoatlantico.com\/blog\/?p=414"},"modified":"2013-11-23T16:18:33","modified_gmt":"2013-11-23T16:18:33","slug":"agua-limpia-para-un-mundo-sano","status":"publish","type":"post","link":"https:\/\/www.talasoatlantico.com\/blog\/agua-limpia-para-un-mundo-sano\/","title":{"rendered":"Agua limpia para un mundo sano"},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/_u_dwr43mzZg\/S6gUXkOMPvI\/AAAAAAAAAFU\/a8aDKdFbNM0\/s1600-h\/dia+mundial+auga.jpg\"><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/_u_dwr43mzZg\/S6gUXkOMPvI\/AAAAAAAAAFU\/a8aDKdFbNM0\/s320\/dia+mundial+auga.jpg\" border=\"0\" alt=\"\"><\/a><br \/><span>Mensaje con motivo del D\u00eda Mundial del Agua 2010 de la Directora General de la Unesco<br \/><\/span><span><\/p>\n<p><b><span>\u201cAgua limpia para un mundo sano\u201d  &#8211; 22 de marzo de 2010<\/p>\n<p><\/span><\/b><\/p>\n<p><b><\/p>\n<p><span> <\/span><\/p>\n<p><\/b><\/p>\n<p><span>El agua es fundamental para la vida en la Tierra. Para que los grupos humanos y los ecosistemas puedan prosperar, esa agua debe ser limpia, permanecer limpia y, m\u00e1s importante a\u00fan, debe estar al alcance de todos.<\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>El D\u00eda Mundial del Agua 2010 tiene por lema \u201cAgua limpia para un mundo sano\u201d. Al celebrar este D\u00eda Mundial, examinemos los hechos. M\u00e1s de 2.500 millones de seres humanos carecen hoy de sistemas sanitarios adecuados. Se calcula que 884 millones de personas, la mayor\u00eda de ellas africanas, no tienen acceso al agua potable. Alrededor de 1,5 millones de ni\u00f1os menores de cinco a\u00f1os mueren anualmente a causa de enfermedades transmitidas por el agua. El deterioro de la calidad de las aguas en r\u00edos, arroyos, lagos y mantos fre\u00e1ticos tiene consecuencias directas sobre los ecosistemas y la salud humana. Esta situaci\u00f3n constituye una tragedia humana indescriptible y un obst\u00e1culo importante para el desarrollo.<\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>Las enfermedades vinculadas al agua, y los trastornos financieros que acarrean, reducen las posibilidades de que las familias pobres consigan educar a sus hijos. A su vez, esta situaci\u00f3n priva a la nueva generaci\u00f3n de la oportunidad de mejorar sus propias condiciones de vida y de romper el c\u00edrculo vicioso de pobreza y escasez en que est\u00e1 atrapada. Agua limpia e instalaciones sanitarias adecuadas son el punto de partida. Todo m\u00e9todo clave para tratar los problemas que plantea la calidad del agua debe basarse en la prevenci\u00f3n de la contaminaci\u00f3n y las estrategias de control y restauraci\u00f3n. <\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>Numerosos r\u00edos, que fueron anta\u00f1o fuente de prosperidad y albergue de rica fauna, est\u00e1n ahora gravemente contaminados. El deterioro de la calidad del agua en la superficie y en los sistemas fre\u00e1ticos est\u00e1 agravando la escasez de recursos h\u00eddricos, con repercusiones negativas en nuestro entorno natural y los bienes y servicios vinculados al ecosistema que \u00e9ste ofrece, poniendo en peligro la seguridad alimentaria y los medios de subsistencia.<\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>En esta \u00e9poca de restricci\u00f3n de gastos, cuando las dificultades econ\u00f3micas comprometen las inversiones destinadas al desarrollo, debemos decir claramente que los avances en materia de desarrollo se autofinancian con creces. Se calcula que el logro de los Objetivos de Desarrollo del Milenio en lo relativo al acceso a agua limpia y servicios sanitarios generar\u00eda un ahorro superior a los 84.000 millones de d\u00f3lares. Disponemos ya de los conocimientos cient\u00edficos necesarios para realizar grandes progresos en el suministro de agua limpia y equipos sanitarios, siempre y cuando pueda obtenerse la financiaci\u00f3n necesaria. Los investigadores est\u00e1n creando nuevos e ingeniosos m\u00e9todos para proteger de la contaminaci\u00f3n las aguas de superficie y los mantos fre\u00e1ticos, y garantizar as\u00ed una mejor gesti\u00f3n de los recursos h\u00eddricos. <\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>En su calidad de organismo rector de las Naciones Unidas para la ciencia y la educaci\u00f3n relativas al agua, la UNESCO impulsa toda una gama de programas con miras a ampliar estas competencias. El Programa Hidrol\u00f3gico Internacional de la UNESCO participa activamente en el fomento de la ciencia y el conocimiento para proteger la calidad de las aguas superficiales y los sistemas fre\u00e1ticos. Asimismo, la Organizaci\u00f3n contribuye a la vigilancia del estado de los recursos de agua dulce del planeta mediante el Informe sobre el Desarrollo de los Recursos H\u00eddricos en el Mundo coordinado por el Programa Mundial de Evaluaci\u00f3n de los Recursos H\u00eddricos, cuya secretar\u00eda la UNESCO acoge y orienta. Desde 2003, la UNESCO ha supervisado la formaci\u00f3n en materia de recursos h\u00eddricos de docenas de cient\u00edficos e ingenieros de pa\u00edses en desarrollo, en el Instituto UNESCO-IHE para la Educaci\u00f3n relativa al Agua, una instituci\u00f3n de categor\u00eda mundial con sede en los Pa\u00edses Bajos. <\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>Asimismo, la UNESCO promueve la creaci\u00f3n de capacidades con miras a una mejor ordenaci\u00f3n de los recursos h\u00eddricos mediante los centros y las c\u00e1tedras sobre el agua que auspicia en diversas partes del mundo. <\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>A\u00fan queda mucho por hacer si queremos mejorar la vida de millones de personas. En este D\u00eda Mundial del Agua, exhorto a los gobiernos, la sociedad civil, el sector privado y todas las partes interesadas a que pongan el objetivo de \u201cAgua limpia para un mundo sano\u201d entre sus principales prioridades. <\/p>\n<p><\/span><\/p>\n<p><p><span> <\/span><\/p>\n<\/p>\n<p><span>Irina Bokova<\/p>\n<p><\/span><\/p>\n<p><b><a href=\"http:\/\/unesdoc.unesco.org\/images\/0018\/001872\/187217s.pdf\"><span>Mensaje de la Sra. Irina Bokova, Directora General de la UNESCO, con motivo del D\u00eda Mundial del Agua<\/span><\/a><\/b><\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mensaje con motivo del D\u00eda Mundial del Agua 2010 de la Directora General de la Unesco \u201cAgua limpia para un mundo sano\u201d &#8211; 22 de marzo de 2010 El agua es fundamental para la vida en la Tierra. Para que los grupos humanos y los ecosistemas puedan prosperar, esa agua debe ser limpia, permanecer limpia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/414"}],"collection":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":1,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"predecessor-version":[{"id":1159,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/posts\/414\/revisions\/1159"}],"wp:attachment":[{"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/categories?post=414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.talasoatlantico.com\/blog\/wp-json\/wp\/v2\/tags?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}